{"id":2387,"date":"2017-10-25T14:44:11","date_gmt":"2017-10-25T12:44:11","guid":{"rendered":"http:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png"},"modified":"2017-10-25T14:44:11","modified_gmt":"2017-10-25T12:44:11","slug":"teaser_news_kinderzeichnung_koenigin","status":"inherit","type":"attachment","link":"https:\/\/www.sternenfee-kita.de\/en\/startseite-2\/teaser_news_kinderzeichnung_koenigin\/","title":{"rendered":"Teaser_News_Kinderzeichnung_Koenigin"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2387","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png\" \/>\n<meta property=\"og:site_name\" content=\"Kita Sternenfee\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-1024x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Teaser_News_Kinderzeichnung_Koenigin.png\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Teaser_News_Kinderzeichnung_Koenigin.png\",\"name\":\"Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\"},\"datePublished\":\"2017-10-25T12:44:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Teaser_News_Kinderzeichnung_Koenigin.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Teaser_News_Kinderzeichnung_Koenigin.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Teaser_News_Kinderzeichnung_Koenigin.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Teaser_News_Kinderzeichnung_Koenigin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/\",\"name\":\"Kita Sternenfee\",\"description\":\"in M\u00fcnchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","og_locale":"en_US","og_type":"article","og_title":"Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee","og_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","og_site_name":"Kita Sternenfee","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-1024x768.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","name":"Teaser_News_Kinderzeichnung_Koenigin - Kita Sternenfee","isPartOf":{"@id":"https:\/\/www.sternenfee-kita.de\/#website"},"datePublished":"2017-10-25T12:44:11+00:00","breadcrumb":{"@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/en\/"},{"@type":"ListItem","position":2,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/en\/"},{"@type":"ListItem","position":3,"name":"Teaser_News_Kinderzeichnung_Koenigin"}]},{"@type":"WebSite","@id":"https:\/\/www.sternenfee-kita.de\/#website","url":"https:\/\/www.sternenfee-kita.de\/","name":"Kita Sternenfee","description":"in M\u00fcnchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sternenfee-kita.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-300x225.png 300w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-768x576.png 768w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-1024x768.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":3648,"height":2736,"file":"2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","sizes":{"thumbnail":{"file":"Teaser_News_Kinderzeichnung_Koenigin-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-150x150.png"},"medium":{"file":"Teaser_News_Kinderzeichnung_Koenigin-300x225.png","width":300,"height":225,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-300x225.png"},"medium_large":{"file":"Teaser_News_Kinderzeichnung_Koenigin-768x576.png","width":768,"height":576,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-768x576.png"},"large":{"file":"Teaser_News_Kinderzeichnung_Koenigin-1024x768.png","width":1024,"height":768,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin-1024x768.png"},"full":{"file":"Teaser_News_Kinderzeichnung_Koenigin.png","width":3648,"height":2736,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2379,"source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/08\/Teaser_News_Kinderzeichnung_Koenigin.png","filename":"Teaser_News_Kinderzeichnung_Koenigin.png","filesize":4530097,"_links":{"self":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/media\/2387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/comments?post=2387"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2379,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/pages\/2379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}