{"id":2768,"date":"2017-10-25T14:38:27","date_gmt":"2017-10-25T12:38:27","guid":{"rendered":"http:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg"},"modified":"2017-10-25T14:38:27","modified_gmt":"2017-10-25T12:38:27","slug":"spezialthemen_vorschulkinder_sternenfee_bildungsimage_172_0595-2","status":"inherit","type":"attachment","link":"https:\/\/www.sternenfee-kita.de\/en\/konzept\/spezialthemen_vorschulkinder_sternenfee_bildungsimage_172_0595-2\/","title":{"rendered":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2768","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Kita Sternenfee\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg\",\"name\":\"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\"},\"datePublished\":\"2017-10-25T12:38:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konzept\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/en\\\/konzept\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/\",\"name\":\"Kita Sternenfee\",\"description\":\"in M\u00fcnchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","og_locale":"en_US","og_type":"article","og_title":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee","og_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","og_site_name":"Kita Sternenfee","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","name":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595 - Kita Sternenfee","isPartOf":{"@id":"https:\/\/www.sternenfee-kita.de\/#website"},"datePublished":"2017-10-25T12:38:27+00:00","breadcrumb":{"@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/en\/"},{"@type":"ListItem","position":2,"name":"Konzept","item":"https:\/\/www.sternenfee-kita.de\/en\/konzept\/"},{"@type":"ListItem","position":3,"name":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595"}]},{"@type":"WebSite","@id":"https:\/\/www.sternenfee-kita.de\/#website","url":"https:\/\/www.sternenfee-kita.de\/","name":"Kita Sternenfee","description":"in M\u00fcnchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sternenfee-kita.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-300x200.jpg 300w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-768x512.jpg 768w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-1024x683.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":5760,"height":3840,"file":"2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","sizes":{"thumbnail":{"file":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-150x150.jpg"},"medium":{"file":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-300x200.jpg"},"medium_large":{"file":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-768x512.jpg"},"large":{"file":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595-1024x683.jpg"},"full":{"file":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","width":5760,"height":3840,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg"}},"image_meta":{"aperture":"2.8","credit":"Mercier Nicolas","camera":"Canon EOS 5D Mark III","caption":"","created_timestamp":"1497344333","copyright":"bildungsimage.de","focal_length":"85","iso":"500","shutter_speed":"0.00625","title":"","orientation":"0","keywords":[]}},"post":2435,"source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2017\/10\/Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","filename":"Spezialthemen_Vorschulkinder_Sternenfee_bildungsimage_172_0595.jpg","filesize":2846217,"_links":{"self":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/media\/2768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/comments?post=2768"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2435,"href":"https:\/\/www.sternenfee-kita.de\/en\/wp-json\/wp\/v2\/pages\/2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}