{"id":2523,"date":"2018-05-24T16:58:59","date_gmt":"2018-05-24T14:58:59","guid":{"rendered":"http:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg"},"modified":"2018-05-24T16:58:59","modified_gmt":"2018-05-24T14:58:59","slug":"sternenfee_start_galerie_2c","status":"inherit","type":"attachment","link":"https:\/\/www.sternenfee-kita.de\/es\/startseite-2\/sternenfee_start_galerie_2c\/","title":{"rendered":"Sternenfee_Start_Galerie_2c"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2523","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sternenfee_Start_Galerie_2c - Kita Sternenfee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sternenfee_Start_Galerie_2c - Kita Sternenfee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Kita Sternenfee\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Sternenfee_Start_Galerie_2c.jpg\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Sternenfee_Start_Galerie_2c.jpg\",\"name\":\"Sternenfee_Start_Galerie_2c - Kita Sternenfee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\"},\"datePublished\":\"2018-05-24T14:58:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Sternenfee_Start_Galerie_2c.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Sternenfee_Start_Galerie_2c.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Sternenfee_Start_Galerie_2c.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sternenfee_Start_Galerie_2c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/\",\"name\":\"Kita Sternenfee\",\"description\":\"in M\u00fcnchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sternenfee_Start_Galerie_2c - Kita Sternenfee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","og_locale":"es_ES","og_type":"article","og_title":"Sternenfee_Start_Galerie_2c - Kita Sternenfee","og_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","og_site_name":"Kita Sternenfee","og_image":[{"width":800,"height":700,"url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","name":"Sternenfee_Start_Galerie_2c - Kita Sternenfee","isPartOf":{"@id":"https:\/\/www.sternenfee-kita.de\/#website"},"datePublished":"2018-05-24T14:58:59+00:00","breadcrumb":{"@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/es\/"},{"@type":"ListItem","position":2,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/es\/"},{"@type":"ListItem","position":3,"name":"Sternenfee_Start_Galerie_2c"}]},{"@type":"WebSite","@id":"https:\/\/www.sternenfee-kita.de\/#website","url":"https:\/\/www.sternenfee-kita.de\/","name":"Kita Sternenfee","description":"in M\u00fcnchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sternenfee-kita.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg'><img decoding=\"async\" width=\"300\" height=\"263\" src=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-300x263.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-300x263.jpg 300w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-768x672.jpg 768w, https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":700,"file":"2018\/05\/Sternenfee_Start_Galerie_2c.jpg","sizes":{"thumbnail":{"file":"Sternenfee_Start_Galerie_2c-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-150x150.jpg"},"medium":{"file":"Sternenfee_Start_Galerie_2c-300x263.jpg","width":300,"height":263,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-300x263.jpg"},"medium_large":{"file":"Sternenfee_Start_Galerie_2c-768x672.jpg","width":768,"height":672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c-768x672.jpg"},"full":{"file":"Sternenfee_Start_Galerie_2c.jpg","width":800,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2498,"source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2018\/05\/Sternenfee_Start_Galerie_2c.jpg","filename":"Sternenfee_Start_Galerie_2c.jpg","filesize":204599,"_links":{"self":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/media\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/comments?post=2523"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2498,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/pages\/2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}