{"id":3040,"date":"2020-03-01T12:12:02","date_gmt":"2020-03-01T11:12:02","guid":{"rendered":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png"},"modified":"2020-03-01T12:12:02","modified_gmt":"2020-03-01T11:12:02","slug":"ichkannkochen-2","status":"inherit","type":"attachment","link":"https:\/\/www.sternenfee-kita.de\/es\/2020\/03\/01\/ich-kann-kochen\/ichkannkochen-2\/","title":{"rendered":"IchKannKochen"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3040","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IchKannKochen - Kita Sternenfee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IchKannKochen - Kita Sternenfee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png\" \/>\n<meta property=\"og:site_name\" content=\"Kita Sternenfee\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"279\" \/>\n\t<meta property=\"og:image:height\" content=\"234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IchKannKochen.png\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IchKannKochen.png\",\"name\":\"IchKannKochen - Kita Sternenfee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\"},\"datePublished\":\"2020-03-01T11:12:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IchKannKochen.png#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IchKannKochen.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IchKannKochen.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1S\u00e9 cocinar! \u00a1Estamos a bordo!\",\"item\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/es\\\/2020\\\/03\\\/01\\\/ich-kann-kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IchKannKochen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/#website\",\"url\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/\",\"name\":\"Kita Sternenfee\",\"description\":\"in M\u00fcnchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sternenfee-kita.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IchKannKochen - Kita Sternenfee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","og_locale":"es_ES","og_type":"article","og_title":"IchKannKochen - Kita Sternenfee","og_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","og_site_name":"Kita Sternenfee","og_image":[{"width":279,"height":234,"url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","name":"IchKannKochen - Kita Sternenfee","isPartOf":{"@id":"https:\/\/www.sternenfee-kita.de\/#website"},"datePublished":"2020-03-01T11:12:02+00:00","breadcrumb":{"@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sternenfee-kita.de\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1S\u00e9 cocinar! \u00a1Estamos a bordo!","item":"https:\/\/www.sternenfee-kita.de\/es\/2020\/03\/01\/ich-kann-kochen\/"},{"@type":"ListItem","position":3,"name":"IchKannKochen"}]},{"@type":"WebSite","@id":"https:\/\/www.sternenfee-kita.de\/#website","url":"https:\/\/www.sternenfee-kita.de\/","name":"Kita Sternenfee","description":"in M\u00fcnchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sternenfee-kita.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png'><img decoding=\"async\" width=\"279\" height=\"234\" src=\"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":279,"height":234,"file":"2020\/03\/IchKannKochen.png","sizes":{"thumbnail":{"file":"IchKannKochen-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen-150x150.png"},"full":{"file":"IchKannKochen.png","width":279,"height":234,"mime_type":"image\/png","source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2546,"source_url":"https:\/\/www.sternenfee-kita.de\/wp-content\/uploads\/2020\/03\/IchKannKochen.png","filename":"IchKannKochen.png","filesize":28785,"_links":{"self":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/media\/3040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/comments?post=3040"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2546,"href":"https:\/\/www.sternenfee-kita.de\/es\/wp-json\/wp\/v2\/posts\/2546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}